{"id":12017,"date":"2025-02-04T20:13:43","date_gmt":"2025-02-04T17:13:43","guid":{"rendered":"https:\/\/transgor.com\/?page_id=12017"},"modified":"2026-03-09T18:37:53","modified_gmt":"2026-03-09T15:37:53","slug":"road-transport","status":"publish","type":"page","link":"https:\/\/transgor.com\/en\/road-transport\/","title":{"rendered":"Road transport"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":10922,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12017","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Road transport - Transgor Logistik - International Transport<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/transgor.com\/en\/road-transport\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Road transport - Transgor Logistik - International Transport\" \/>\n<meta property=\"og:url\" content=\"https:\/\/transgor.com\/en\/road-transport\/\" \/>\n<meta property=\"og:site_name\" content=\"Transgor Logistik - International Transport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/transgor\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T15:37:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/transgor.com\/wp-content\/uploads\/2024\/09\/IMAG2100-scaled-1-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"563\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/road-transport\\\/\",\"url\":\"https:\\\/\\\/transgor.com\\\/en\\\/road-transport\\\/\",\"name\":\"Road transport - Transgor Logistik - International Transport\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/road-transport\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/road-transport\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/transgor.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMAG2100-scaled-1-1.webp\",\"datePublished\":\"2025-02-04T17:13:43+00:00\",\"dateModified\":\"2026-03-09T15:37:53+00:00\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/transgor.com\\\/en\\\/road-transport\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/road-transport\\\/#primaryimage\",\"url\":\"https:\\\/\\\/transgor.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMAG2100-scaled-1-1.webp\",\"contentUrl\":\"https:\\\/\\\/transgor.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/IMAG2100-scaled-1-1.webp\",\"width\":1000,\"height\":563,\"caption\":\"camion-transgor\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/transgor.com\\\/en\\\/\",\"name\":\"Transgor Logistik - International Transport\",\"description\":\"TRANSPORT, LOGISTIC\u0102 &amp; SERVICII\",\"publisher\":{\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/transgor.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/#organization\",\"name\":\"Transgor Logistik - International Transport\",\"url\":\"https:\\\/\\\/transgor.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/transgor.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/favicon.png\",\"contentUrl\":\"https:\\\/\\\/transgor.com\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/favicon.png\",\"width\":226,\"height\":226,\"caption\":\"Transgor Logistik - International Transport\"},\"image\":{\"@id\":\"https:\\\/\\\/transgor.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/transgor\\\/\",\"https:\\\/\\\/www.instagram.com\\\/transgor_logistik\\\/?igsh=MWQ5a2k2OWU3bDVqag\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/transgor-logistik\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Road transport - Transgor Logistik - International Transport","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/transgor.com\/en\/road-transport\/","og_locale":"en_US","og_type":"article","og_title":"Road transport - Transgor Logistik - International Transport","og_url":"https:\/\/transgor.com\/en\/road-transport\/","og_site_name":"Transgor Logistik - International Transport","article_publisher":"https:\/\/www.facebook.com\/transgor\/","article_modified_time":"2026-03-09T15:37:53+00:00","og_image":[{"width":1000,"height":563,"url":"https:\/\/transgor.com\/wp-content\/uploads\/2024\/09\/IMAG2100-scaled-1-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/transgor.com\/en\/road-transport\/","url":"https:\/\/transgor.com\/en\/road-transport\/","name":"Road transport - Transgor Logistik - International Transport","isPartOf":{"@id":"https:\/\/transgor.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/transgor.com\/en\/road-transport\/#primaryimage"},"image":{"@id":"https:\/\/transgor.com\/en\/road-transport\/#primaryimage"},"thumbnailUrl":"https:\/\/transgor.com\/wp-content\/uploads\/2024\/09\/IMAG2100-scaled-1-1.webp","datePublished":"2025-02-04T17:13:43+00:00","dateModified":"2026-03-09T15:37:53+00:00","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/transgor.com\/en\/road-transport\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/transgor.com\/en\/road-transport\/#primaryimage","url":"https:\/\/transgor.com\/wp-content\/uploads\/2024\/09\/IMAG2100-scaled-1-1.webp","contentUrl":"https:\/\/transgor.com\/wp-content\/uploads\/2024\/09\/IMAG2100-scaled-1-1.webp","width":1000,"height":563,"caption":"camion-transgor"},{"@type":"WebSite","@id":"https:\/\/transgor.com\/en\/#website","url":"https:\/\/transgor.com\/en\/","name":"Transgor Logistik - International Transport","description":"TRANSPORT, LOGISTIC\u0102 &amp; SERVICII","publisher":{"@id":"https:\/\/transgor.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/transgor.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/transgor.com\/en\/#organization","name":"Transgor Logistik - International Transport","url":"https:\/\/transgor.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/transgor.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/transgor.com\/wp-content\/uploads\/2024\/08\/favicon.png","contentUrl":"https:\/\/transgor.com\/wp-content\/uploads\/2024\/08\/favicon.png","width":226,"height":226,"caption":"Transgor Logistik - International Transport"},"image":{"@id":"https:\/\/transgor.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/transgor\/","https:\/\/www.instagram.com\/transgor_logistik\/?igsh=MWQ5a2k2OWU3bDVqag","https:\/\/www.linkedin.com\/company\/transgor-logistik\/"]}]}},"_links":{"self":[{"href":"https:\/\/transgor.com\/en\/wp-json\/wp\/v2\/pages\/12017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/transgor.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/transgor.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/transgor.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/transgor.com\/en\/wp-json\/wp\/v2\/comments?post=12017"}],"version-history":[{"count":5,"href":"https:\/\/transgor.com\/en\/wp-json\/wp\/v2\/pages\/12017\/revisions"}],"predecessor-version":[{"id":15104,"href":"https:\/\/transgor.com\/en\/wp-json\/wp\/v2\/pages\/12017\/revisions\/15104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/transgor.com\/en\/wp-json\/wp\/v2\/media\/10922"}],"wp:attachment":[{"href":"https:\/\/transgor.com\/en\/wp-json\/wp\/v2\/media?parent=12017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}